{"id":6856,"date":"2013-11-24T19:05:42","date_gmt":"2013-11-24T19:05:42","guid":{"rendered":"http:\/\/socoolhostelporto.com\/madredeus-casa-da-musica-2\/"},"modified":"2020-01-22T15:23:33","modified_gmt":"2020-01-22T15:23:33","slug":"madredeus-casa-da-musica","status":"publish","type":"post","link":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/","title":{"rendered":"Madredeus &#8211; Casa da M\u00fasica"},"content":{"rendered":"<p>15 December 2013.<br \/>\nCasa da M\u00fasica.<\/p>\n<p>Need accommodation in Porto for this event?<br \/>\n<a title=\"So Cool Hostel Porto\" href=\"http:\/\/socoolhostelporto.com\/\">www.socoolhostelporto.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>15 December 2013. Casa da M\u00fasica. Need accommodation in Porto  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":6852,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[88,89],"class_list":["post-6856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musica","tag-concertos","tag-eventos-culturais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madredeus - Casa da M\u00fasica - So Cool Hostel Porto<\/title>\n<meta name=\"description\" content=\"Madredeus - Casa da M\u00fasica. 15 December 2013. Need accommodation in Porto for this event? www.socoolhostelporto.com\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madredeus - Casa da M\u00fasica - So Cool Hostel Porto\" \/>\n<meta property=\"og:description\" content=\"Madredeus - Casa da M\u00fasica. 15 December 2013. Need accommodation in Porto for this event? www.socoolhostelporto.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/\" \/>\n<meta property=\"og:site_name\" content=\"So Cool Hostel Porto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/socoolhostelporto\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/socoolhostelporto\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-24T19:05:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-22T15:23:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"socoolmasterdb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@socoolhostel\" \/>\n<meta name=\"twitter:site\" content=\"@socoolhostel\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"socoolmasterdb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/\"},\"author\":{\"name\":\"socoolmasterdb\",\"@id\":\"https:\/\/socoolhostelporto.com\/#\/schema\/person\/98f421a6fd34ef8f3dbaac5ac6042129\"},\"headline\":\"Madredeus &#8211; Casa da M\u00fasica\",\"datePublished\":\"2013-11-24T19:05:42+00:00\",\"dateModified\":\"2020-01-22T15:23:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/\"},\"wordCount\":21,\"publisher\":{\"@id\":\"https:\/\/socoolhostelporto.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg\",\"keywords\":[\"Concertos\",\"Eventos Culturais\"],\"articleSection\":[\"Musica\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/\",\"url\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/\",\"name\":\"Madredeus - Casa da M\u00fasica - So Cool Hostel Porto\",\"isPartOf\":{\"@id\":\"https:\/\/socoolhostelporto.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg\",\"datePublished\":\"2013-11-24T19:05:42+00:00\",\"dateModified\":\"2020-01-22T15:23:33+00:00\",\"description\":\"Madredeus - Casa da M\u00fasica. 15 December 2013. Need accommodation in Porto for this event? www.socoolhostelporto.com\",\"breadcrumb\":{\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#primaryimage\",\"url\":\"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg\",\"contentUrl\":\"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg\",\"caption\":\"Madredeus - Casa da M\u00fasica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/socoolhostelporto.com\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madredeus &#8211; Casa da M\u00fasica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/socoolhostelporto.com\/#website\",\"url\":\"https:\/\/socoolhostelporto.com\/\",\"name\":\"So Cool Hostel Porto\",\"description\":\"O teu Hostel no Porto!\",\"publisher\":{\"@id\":\"https:\/\/socoolhostelporto.com\/#organization\"},\"alternateName\":\"Socoolhostel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/socoolhostelporto.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/socoolhostelporto.com\/#organization\",\"name\":\"So Cool Hostel Porto\",\"alternateName\":\"SoCoolHostel\",\"url\":\"https:\/\/socoolhostelporto.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/socoolhostelporto.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/socoolhostelporto.png\",\"contentUrl\":\"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/socoolhostelporto.png\",\"width\":105,\"height\":92,\"caption\":\"So Cool Hostel Porto\"},\"image\":{\"@id\":\"https:\/\/socoolhostelporto.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/socoolhostelporto\",\"https:\/\/x.com\/socoolhostel\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/socoolhostelporto.com\/#\/schema\/person\/98f421a6fd34ef8f3dbaac5ac6042129\",\"name\":\"socoolmasterdb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/24e834edf9e7150b310c66e7829b9cee2a6640db62af8ef7c0a25f44732a0e3f?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/24e834edf9e7150b310c66e7829b9cee2a6640db62af8ef7c0a25f44732a0e3f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/24e834edf9e7150b310c66e7829b9cee2a6640db62af8ef7c0a25f44732a0e3f?s=96&d=mm&r=g\",\"caption\":\"socoolmasterdb\"},\"sameAs\":[\"https:\/\/www.facebook.com\/socoolhostelporto\",\"https:\/\/x.com\/socoolhostel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madredeus - Casa da M\u00fasica - So Cool Hostel Porto","description":"Madredeus - Casa da M\u00fasica. 15 December 2013. Need accommodation in Porto for this event? www.socoolhostelporto.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/","og_locale":"pt_PT","og_type":"article","og_title":"Madredeus - Casa da M\u00fasica - So Cool Hostel Porto","og_description":"Madredeus - Casa da M\u00fasica. 15 December 2013. Need accommodation in Porto for this event? www.socoolhostelporto.com","og_url":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/","og_site_name":"So Cool Hostel Porto","article_publisher":"https:\/\/www.facebook.com\/socoolhostelporto","article_author":"https:\/\/www.facebook.com\/socoolhostelporto","article_published_time":"2013-11-24T19:05:42+00:00","article_modified_time":"2020-01-22T15:23:33+00:00","og_image":[{"url":"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"socoolmasterdb","twitter_card":"summary_large_image","twitter_creator":"@socoolhostel","twitter_site":"@socoolhostel","twitter_misc":{"Escrito por":"socoolmasterdb"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#article","isPartOf":{"@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/"},"author":{"name":"socoolmasterdb","@id":"https:\/\/socoolhostelporto.com\/#\/schema\/person\/98f421a6fd34ef8f3dbaac5ac6042129"},"headline":"Madredeus &#8211; Casa da M\u00fasica","datePublished":"2013-11-24T19:05:42+00:00","dateModified":"2020-01-22T15:23:33+00:00","mainEntityOfPage":{"@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/"},"wordCount":21,"publisher":{"@id":"https:\/\/socoolhostelporto.com\/#organization"},"image":{"@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#primaryimage"},"thumbnailUrl":"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg","keywords":["Concertos","Eventos Culturais"],"articleSection":["Musica"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/","url":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/","name":"Madredeus - Casa da M\u00fasica - So Cool Hostel Porto","isPartOf":{"@id":"https:\/\/socoolhostelporto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#primaryimage"},"image":{"@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#primaryimage"},"thumbnailUrl":"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg","datePublished":"2013-11-24T19:05:42+00:00","dateModified":"2020-01-22T15:23:33+00:00","description":"Madredeus - Casa da M\u00fasica. 15 December 2013. Need accommodation in Porto for this event? www.socoolhostelporto.com","breadcrumb":{"@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#primaryimage","url":"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg","contentUrl":"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/2013\/11\/madredeus-casa-da-musica-2013.jpg","caption":"Madredeus - Casa da M\u00fasica"},{"@type":"BreadcrumbList","@id":"https:\/\/socoolhostelporto.com\/pt-pt\/madredeus-casa-da-musica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/socoolhostelporto.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Madredeus &#8211; Casa da M\u00fasica"}]},{"@type":"WebSite","@id":"https:\/\/socoolhostelporto.com\/#website","url":"https:\/\/socoolhostelporto.com\/","name":"So Cool Hostel Porto","description":"O teu Hostel no Porto!","publisher":{"@id":"https:\/\/socoolhostelporto.com\/#organization"},"alternateName":"Socoolhostel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/socoolhostelporto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/socoolhostelporto.com\/#organization","name":"So Cool Hostel Porto","alternateName":"SoCoolHostel","url":"https:\/\/socoolhostelporto.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/socoolhostelporto.com\/#\/schema\/logo\/image\/","url":"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/socoolhostelporto.png","contentUrl":"https:\/\/socoolhostelporto.com\/wp-content\/uploads\/socoolhostelporto.png","width":105,"height":92,"caption":"So Cool Hostel Porto"},"image":{"@id":"https:\/\/socoolhostelporto.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/socoolhostelporto","https:\/\/x.com\/socoolhostel"]},{"@type":"Person","@id":"https:\/\/socoolhostelporto.com\/#\/schema\/person\/98f421a6fd34ef8f3dbaac5ac6042129","name":"socoolmasterdb","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/24e834edf9e7150b310c66e7829b9cee2a6640db62af8ef7c0a25f44732a0e3f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/24e834edf9e7150b310c66e7829b9cee2a6640db62af8ef7c0a25f44732a0e3f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/24e834edf9e7150b310c66e7829b9cee2a6640db62af8ef7c0a25f44732a0e3f?s=96&d=mm&r=g","caption":"socoolmasterdb"},"sameAs":["https:\/\/www.facebook.com\/socoolhostelporto","https:\/\/x.com\/socoolhostel"]}]}},"_links":{"self":[{"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=6856"}],"version-history":[{"count":1,"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6856\/revisions"}],"predecessor-version":[{"id":6857,"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6856\/revisions\/6857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/media\/6852"}],"wp:attachment":[{"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=6856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=6856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/socoolhostelporto.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=6856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}